{"id":19360,"date":"2026-05-12T18:59:04","date_gmt":"2026-05-12T22:59:04","guid":{"rendered":"https:\/\/diarioellabrador.cl\/?p=19360"},"modified":"2026-05-12T18:59:06","modified_gmt":"2026-05-12T22:59:06","slug":"autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina","status":"publish","type":"post","link":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/","title":{"rendered":"Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>La actividad reuni\u00f3 adem\u00e1s a artesanos y organizaciones locales en Plaza de Armas de Melipilla, dando inicio a una de las celebraciones m\u00e1s relevantes de la localidad locera.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con una muestra de alfarer\u00eda, orfebrer\u00eda y gastronom\u00eda t\u00edpica de Pomaire, se realiz\u00f3 en Plaza de Armas de Melipilla el lanzamiento oficial de la 72\u00b0 versi\u00f3n de la Semana Pomairina, tradicional festividad que se desarrollar\u00e1 entre el 16 y el 24 de mayo.<\/p>\n\n\n\n<p>La ceremonia cont\u00f3 con la participaci\u00f3n del delegado presidencial provincial de Melipilla, Gast\u00f3n Libuy; la alcaldesa de Melipilla, Paula G\u00e1rate; el presidente de la Junta de Vecinos de Pomaire, Rodrigo Toledo; la presidenta de la Agrupaci\u00f3n de Mujeres Alfareras de Pomaire, Carla Aguirre; adem\u00e1s de representantes de organizaciones locales, artesanos y vecinos de la comuna.<\/p>\n\n\n\n<p>Tras la ceremonia, el delegado provincial de Melipilla, Gast\u00f3n Libuy, destac\u00f3 el valor patrimonial, cultural y tur\u00edstico de Pomaire, localidad reconocida a nivel nacional por su tradici\u00f3n alfarera y su variada oferta en artesan\u00edas y gastronom\u00eda t\u00edpica de Chile.<\/p>\n\n\n\n<p>\u201cFelicitar al Municipio de Melipilla y a su alcaldesa Paula G\u00e1rate, por haber promovido y fortalecido esta 72\u00b0 versi\u00f3n de la Semana Pomairina. Esta es una actividad tradicional de la comuna de Melipilla, que nosotros vamos a seguir promoviendo, vamos a participar y acompa\u00f1ar a la comunidad de Pomaire, en que hago un llamado a los vecinos de la provincia a visitarla en la semana Pomairina, donde habr\u00e1 muchas actividades, stand y degustaciones. Un panorama familiar que quisiera relevar e invitar a las familias de la provincia\u201d, indic\u00f3.<\/p>\n\n\n\n<p>Por su parte, alcaldesa de Melipilla, Paula G\u00e1rate, destac\u00f3 que esta celebraci\u00f3n representa una importante vitrina para los artesanos y alfareros de la localidad. \u201cEs el lanzamiento oficial de la Semana Pomairina, la cual se desarrollar\u00e1 entre el 16 y el 24 de mayo. Esta es una invitaci\u00f3n a todos los vecinos de Melipilla, Regi\u00f3n Metropolitana y alrededores a que vengan a pasear a Pomaire. Tenemos gastronom\u00eda, artesan\u00eda, alfareras, lugares t\u00edpicos, y el gran panorama cultural que es Pomaire para nosotros. Hoy estamos organizando con la Junta de Vecinos, organizaciones de alfareras de Pomaire y artesanos esta actividad, que es muy importante para ellos. Es un panorama imperdible, donde tenemos una gran oferta de alfarer\u00eda nacional\u201d, reiterando la invitaci\u00f3n a la comunidad a participar de la nueva edici\u00f3n de la Semana Pomairina.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una muestra de alfarer\u00eda, orfebrer\u00eda y gastronom\u00eda t\u00edpica de Pomaire, se realiz\u00f3 en Plaza de Armas de Melipilla el lanzamiento oficial de la 72\u00b0 versi\u00f3n de la Semana Pomairina, tradicional festividad que se desarrollar\u00e1 entre el 16 y el 24 de mayo. La ceremonia cont\u00f3 con la participaci\u00f3n del delegado presidencial provincial de Melipilla,<\/p>\n<div class=\"read-more-wrapper\"><a class=\"read-more\" href=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/\" title=\"Leer m\u00e1s\"> <span class=\"button \">Leer m\u00e1s<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":19316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina - Diario El Labrador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina - Diario El Labrador\" \/>\n<meta property=\"og:description\" content=\"Con una muestra de alfarer\u00eda, orfebrer\u00eda y gastronom\u00eda t\u00edpica de Pomaire, se realiz\u00f3 en Plaza de Armas de Melipilla el lanzamiento oficial de la 72\u00b0 versi\u00f3n de la Semana Pomairina, tradicional festividad que se desarrollar\u00e1 entre el 16 y el 24 de mayo. La ceremonia cont\u00f3 con la participaci\u00f3n del delegado presidencial provincial de Melipilla, Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Labrador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/profile.php?id=61576120840621\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T22:59:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T22:59:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Autoridades-participan-de-lanzamiento-de-la-72\u00b0-Semana-Pomairina-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ElLabradorOf\" \/>\n<meta name=\"twitter:site\" content=\"@ElLabradorOf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/\"},\"author\":{\"name\":\"Editor\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/person\\\/bc25ff80b4563f9c7f4bd7855df01685\"},\"headline\":\"Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina\",\"datePublished\":\"2026-05-12T22:59:04+00:00\",\"dateModified\":\"2026-05-12T22:59:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/\"},\"wordCount\":418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Autoridades-participan-de-lanzamiento-de-la-72\u00b0-Semana-Pomairina-1-scaled.jpg\",\"articleSection\":[\"Cr\u00f3nica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/\",\"name\":\"Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina - Diario El Labrador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Autoridades-participan-de-lanzamiento-de-la-72\u00b0-Semana-Pomairina-1-scaled.jpg\",\"datePublished\":\"2026-05-12T22:59:04+00:00\",\"dateModified\":\"2026-05-12T22:59:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Autoridades-participan-de-lanzamiento-de-la-72\u00b0-Semana-Pomairina-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Autoridades-participan-de-lanzamiento-de-la-72\u00b0-Semana-Pomairina-1-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diarioellabrador.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#website\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/\",\"name\":\"Diario El Labrador\",\"description\":\"Haciendo noticia desde 1921\",\"publisher\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diarioellabrador.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\",\"name\":\"Diario El Labrador\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-Logo-Icono.png\",\"contentUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-Logo-Icono.png\",\"width\":512,\"height\":512,\"caption\":\"Diario El Labrador\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/profile.php?id=61576120840621\",\"https:\\\/\\\/x.com\\\/ElLabradorOf\",\"https:\\\/\\\/www.instagram.com\\\/diarioellabradoroficial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/person\\\/bc25ff80b4563f9c7f4bd7855df01685\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina - Diario El Labrador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/","og_locale":"es_ES","og_type":"article","og_title":"Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina - Diario El Labrador","og_description":"Con una muestra de alfarer\u00eda, orfebrer\u00eda y gastronom\u00eda t\u00edpica de Pomaire, se realiz\u00f3 en Plaza de Armas de Melipilla el lanzamiento oficial de la 72\u00b0 versi\u00f3n de la Semana Pomairina, tradicional festividad que se desarrollar\u00e1 entre el 16 y el 24 de mayo. La ceremonia cont\u00f3 con la participaci\u00f3n del delegado presidencial provincial de Melipilla, Leer m\u00e1s","og_url":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/","og_site_name":"Diario El Labrador","article_publisher":"https:\/\/web.facebook.com\/profile.php?id=61576120840621","article_published_time":"2026-05-12T22:59:04+00:00","article_modified_time":"2026-05-12T22:59:06+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Autoridades-participan-de-lanzamiento-de-la-72\u00b0-Semana-Pomairina-1-scaled.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_creator":"@ElLabradorOf","twitter_site":"@ElLabradorOf","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/#article","isPartOf":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/"},"author":{"name":"Editor","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/person\/bc25ff80b4563f9c7f4bd7855df01685"},"headline":"Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina","datePublished":"2026-05-12T22:59:04+00:00","dateModified":"2026-05-12T22:59:06+00:00","mainEntityOfPage":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/"},"wordCount":418,"commentCount":0,"publisher":{"@id":"https:\/\/diarioellabrador.cl\/#organization"},"image":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Autoridades-participan-de-lanzamiento-de-la-72\u00b0-Semana-Pomairina-1-scaled.jpg","articleSection":["Cr\u00f3nica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/","url":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/","name":"Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina - Diario El Labrador","isPartOf":{"@id":"https:\/\/diarioellabrador.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/#primaryimage"},"image":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Autoridades-participan-de-lanzamiento-de-la-72\u00b0-Semana-Pomairina-1-scaled.jpg","datePublished":"2026-05-12T22:59:04+00:00","dateModified":"2026-05-12T22:59:06+00:00","breadcrumb":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/#primaryimage","url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Autoridades-participan-de-lanzamiento-de-la-72\u00b0-Semana-Pomairina-1-scaled.jpg","contentUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Autoridades-participan-de-lanzamiento-de-la-72\u00b0-Semana-Pomairina-1-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/autoridades-participan-de-lanzamiento-de-la-72-semana-pomairina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioellabrador.cl\/"},{"@type":"ListItem","position":2,"name":"Autoridades participan de lanzamiento de la 72\u00b0 Semana Pomairina"}]},{"@type":"WebSite","@id":"https:\/\/diarioellabrador.cl\/#website","url":"https:\/\/diarioellabrador.cl\/","name":"Diario El Labrador","description":"Haciendo noticia desde 1921","publisher":{"@id":"https:\/\/diarioellabrador.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioellabrador.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diarioellabrador.cl\/#organization","name":"Diario El Labrador","url":"https:\/\/diarioellabrador.cl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/logo\/image\/","url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2025\/02\/cropped-Logo-Icono.png","contentUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2025\/02\/cropped-Logo-Icono.png","width":512,"height":512,"caption":"Diario El Labrador"},"image":{"@id":"https:\/\/diarioellabrador.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/profile.php?id=61576120840621","https:\/\/x.com\/ElLabradorOf","https:\/\/www.instagram.com\/diarioellabradoroficial\/"]},{"@type":"Person","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/person\/bc25ff80b4563f9c7f4bd7855df01685","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/diarioellabrador.cl\/index.php\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/comments?post=19360"}],"version-history":[{"count":1,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19360\/revisions"}],"predecessor-version":[{"id":19361,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19360\/revisions\/19361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/media\/19316"}],"wp:attachment":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/media?parent=19360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/categories?post=19360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/tags?post=19360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}