{"id":19340,"date":"2026-05-12T18:49:21","date_gmt":"2026-05-12T22:49:21","guid":{"rendered":"https:\/\/diarioellabrador.cl\/?p=19340"},"modified":"2026-05-12T18:49:24","modified_gmt":"2026-05-12T22:49:24","slug":"26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas","status":"publish","type":"post","link":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/","title":{"rendered":"26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas"},"content":{"rendered":"\n<p>En el TOP de Melipilla se realiz\u00f3 la audiencia de juicio oral para imputados por delitos de tr\u00e1fico de drogas y tenencia de armas.<\/p>\n\n\n\n<p>El ente persecutor sostuvo que el d\u00eda 24 de octubre del a\u00f1o 2024, a eso de las 19:00 horas aproximadamente, en circunstancias que un equipo de la SIP de Carabineros se encontraba realizando diligencias por Carlos Avil\u00e9s, en la comuna de Melipilla, se acerc\u00f3 una persona desconocida de sexo femenino, quien de forma an\u00f3nima y reservando su identidad por temor a futuras represalias, se\u00f1al\u00f3 que en un block de Gabriela, donde reside un clan familiar se dedican al tr\u00e1fico de droga y posesi\u00f3n de armas de fuego, quien mantendr\u00eda como guardaespaldas a un sujeto apodado \u201cel soldado colombiano\u201d.<\/p>\n\n\n\n<p>Siguiendo con las diligencias y mientras se encontraban recorriendo dicha avenida direcci\u00f3n al sur, al llegar con las indicaciones antes mencionadas, observaron una persona de sexo masculino, identificada como de iniciales C.A.T.C., quien se aproxima al port\u00f3n met\u00e1lico de color negro y llama a las personas que estar\u00edan en el interior, \u00e9ste le pasa con su mano derecha un billete de color azul a una persona de sexo masculino, identificado como el imputado Demi\u00e1n L.T.&nbsp; le hace entrega de una bolsa peque\u00f1a transparente por mano que conten\u00eda tres envoltorios de nylon transparente contenedores de marihuana.<\/p>\n\n\n\n<p>Con estos antecedentes y al estar ante un delito flagrante de microtr\u00e1fico de droga, es que personal de Carabineros y en virtud de existir signos evidentes de que en el interior de un inmueble se estaba cometiendo un delito, es que proceden a ingresar al domicilio de la poblaci\u00f3n Los Poetas, percat\u00e1ndose que en el patio se encontraban cinco personas de sexo masculino, quienes se encontraban sentados alrededor de una mesa elaborando y dosificando marihuana.<\/p>\n\n\n\n<p>A ra\u00edz de lo anterior y mientras se realizaba el registro de dicha vivienda, el personal policial incaut\u00f3 165 frascos de jarabe sellados de deucotos, 346 bolsas de nylon transparente en su interior 422 gramos de marihuana elaborada, un paquete de marihuana elaborada con un peso de un kilo veintid\u00f3s gramos, bolsa en nylon contenedora de un trozo s\u00f3lido de 837 clorhidrato de coca\u00edna, 42 bolsas peque\u00f1as transparentes las que eran contenedoras de ketamina, droga conocida como Tusi. Una escopeta marca Maverick, 11 cartuchos calibre 12 sin percutir.<\/p>\n\n\n\n<p>El Tribunal dictamin\u00f3 que se condena a Brandon A.G junto a Jeffrey E.H. y Juan G.N. a cumplir la pena de 5 a\u00f1os y 1 d\u00eda de presidio mayor en su grado m\u00ednimo cada uno, como autores de un delito consumado de tr\u00e1fico il\u00edcito de sustancias o drogas estupefacientes o psicotr\u00f3picas.<\/p>\n\n\n\n<p>Que, se condena a Pedro A.C. &nbsp;a cumplir la pena de 8 a\u00f1os de presidio mayor en su grado m\u00ednimo, como autor de un delito consumado de tr\u00e1fico il\u00edcito de sustancias o drogas estupefacientes o psicotr\u00f3picas. Adem\u00e1s, a cumplir la pena \u00fanica de 3 a\u00f1os y 1 d\u00eda de presidio menor en su grado m\u00e1ximo, como autor de un delito consumado de tenencia ilegal de arma de fuego y municiones. Las cuales deber\u00e1 cumplirlas efectivamente, comenzando con la m\u00e1s gravosa.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el TOP de Melipilla se realiz\u00f3 la audiencia de juicio oral para imputados por delitos de tr\u00e1fico de drogas y tenencia de armas. El ente persecutor sostuvo que el d\u00eda 24 de octubre del a\u00f1o 2024, a eso de las 19:00 horas aproximadamente, en circunstancias que un equipo de la SIP de Carabineros se<\/p>\n<div class=\"read-more-wrapper\"><a class=\"read-more\" href=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/\" title=\"Leer m\u00e1s\"> <span class=\"button \">Leer m\u00e1s<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":19303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-19340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas - Diario El Labrador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas - Diario El Labrador\" \/>\n<meta property=\"og:description\" content=\"En el TOP de Melipilla se realiz\u00f3 la audiencia de juicio oral para imputados por delitos de tr\u00e1fico de drogas y tenencia de armas. El ente persecutor sostuvo que el d\u00eda 24 de octubre del a\u00f1o 2024, a eso de las 19:00 horas aproximadamente, en circunstancias que un equipo de la SIP de Carabineros se Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Labrador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/profile.php?id=61576120840621\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T22:49:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T22:49:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-Los-Poetas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ElLabradorOf\" \/>\n<meta name=\"twitter:site\" content=\"@ElLabradorOf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/\"},\"author\":{\"name\":\"Editor\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/person\\\/bc25ff80b4563f9c7f4bd7855df01685\"},\"headline\":\"26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas\",\"datePublished\":\"2026-05-12T22:49:21+00:00\",\"dateModified\":\"2026-05-12T22:49:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/\"},\"wordCount\":564,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-Los-Poetas.jpg\",\"articleSection\":[\"Policial\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/\",\"name\":\"26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas - Diario El Labrador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-Los-Poetas.jpg\",\"datePublished\":\"2026-05-12T22:49:21+00:00\",\"dateModified\":\"2026-05-12T22:49:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-Los-Poetas.jpg\",\"contentUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-Los-Poetas.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diarioellabrador.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#website\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/\",\"name\":\"Diario El Labrador\",\"description\":\"Haciendo noticia desde 1921\",\"publisher\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diarioellabrador.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\",\"name\":\"Diario El Labrador\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-Logo-Icono.png\",\"contentUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-Logo-Icono.png\",\"width\":512,\"height\":512,\"caption\":\"Diario El Labrador\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/profile.php?id=61576120840621\",\"https:\\\/\\\/x.com\\\/ElLabradorOf\",\"https:\\\/\\\/www.instagram.com\\\/diarioellabradoroficial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/person\\\/bc25ff80b4563f9c7f4bd7855df01685\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas - Diario El Labrador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/","og_locale":"es_ES","og_type":"article","og_title":"26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas - Diario El Labrador","og_description":"En el TOP de Melipilla se realiz\u00f3 la audiencia de juicio oral para imputados por delitos de tr\u00e1fico de drogas y tenencia de armas. El ente persecutor sostuvo que el d\u00eda 24 de octubre del a\u00f1o 2024, a eso de las 19:00 horas aproximadamente, en circunstancias que un equipo de la SIP de Carabineros se Leer m\u00e1s","og_url":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/","og_site_name":"Diario El Labrador","article_publisher":"https:\/\/web.facebook.com\/profile.php?id=61576120840621","article_published_time":"2026-05-12T22:49:21+00:00","article_modified_time":"2026-05-12T22:49:24+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-Los-Poetas.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_creator":"@ElLabradorOf","twitter_site":"@ElLabradorOf","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/#article","isPartOf":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/"},"author":{"name":"Editor","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/person\/bc25ff80b4563f9c7f4bd7855df01685"},"headline":"26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas","datePublished":"2026-05-12T22:49:21+00:00","dateModified":"2026-05-12T22:49:24+00:00","mainEntityOfPage":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/"},"wordCount":564,"commentCount":0,"publisher":{"@id":"https:\/\/diarioellabrador.cl\/#organization"},"image":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-Los-Poetas.jpg","articleSection":["Policial"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/","url":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/","name":"26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas - Diario El Labrador","isPartOf":{"@id":"https:\/\/diarioellabrador.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/#primaryimage"},"image":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-Los-Poetas.jpg","datePublished":"2026-05-12T22:49:21+00:00","dateModified":"2026-05-12T22:49:24+00:00","breadcrumb":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/#primaryimage","url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-Los-Poetas.jpg","contentUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-Los-Poetas.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/26-anos-de-carcel-para-clan-dedicado-a-la-venta-de-drogas-en-poblacion-los-poetas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioellabrador.cl\/"},{"@type":"ListItem","position":2,"name":"26 a\u00f1os de c\u00e1rcel para clan dedicado a la venta de drogas en poblaci\u00f3n Los Poetas"}]},{"@type":"WebSite","@id":"https:\/\/diarioellabrador.cl\/#website","url":"https:\/\/diarioellabrador.cl\/","name":"Diario El Labrador","description":"Haciendo noticia desde 1921","publisher":{"@id":"https:\/\/diarioellabrador.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioellabrador.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diarioellabrador.cl\/#organization","name":"Diario El Labrador","url":"https:\/\/diarioellabrador.cl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/logo\/image\/","url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2025\/02\/cropped-Logo-Icono.png","contentUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2025\/02\/cropped-Logo-Icono.png","width":512,"height":512,"caption":"Diario El Labrador"},"image":{"@id":"https:\/\/diarioellabrador.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/profile.php?id=61576120840621","https:\/\/x.com\/ElLabradorOf","https:\/\/www.instagram.com\/diarioellabradoroficial\/"]},{"@type":"Person","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/person\/bc25ff80b4563f9c7f4bd7855df01685","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/diarioellabrador.cl\/index.php\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/comments?post=19340"}],"version-history":[{"count":1,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19340\/revisions"}],"predecessor-version":[{"id":19341,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19340\/revisions\/19341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/media\/19303"}],"wp:attachment":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/media?parent=19340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/categories?post=19340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/tags?post=19340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}