{"id":19336,"date":"2026-05-12T18:47:58","date_gmt":"2026-05-12T22:47:58","guid":{"rendered":"https:\/\/diarioellabrador.cl\/?p=19336"},"modified":"2026-05-12T18:48:01","modified_gmt":"2026-05-12T22:48:01","slug":"una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros","status":"publish","type":"post","link":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/","title":{"rendered":"Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros"},"content":{"rendered":"\n<p>Equipo de emergencias fueron alertados en la ma\u00f1ana de ayer martes de un atropello en las inmediaciones de Vicu\u00f1a Mackenna en Hurtado y Correa, el cual dej\u00f3 como resultado el fallecimiento de un hombre adulto.<\/p>\n\n\n\n<p>De acuerdo a los antecedentes preliminares y declaraci\u00f3n del conductor involucrado, la v\u00edctima se encontraba tendida sobre la calzada al momento de ser impactada por un veh\u00edculo particular, cuyo ocupante permaneci\u00f3 en el lugar, prest\u00f3 auxilio y dio aviso a los servicios de emergencia.<\/p>\n\n\n\n<p>Por instrucci\u00f3n de la Fiscal\u00eda Local, personal de la Secci\u00f3n de Accidentes de Tr\u00e1nsito, SIAT de carabineros, realiz\u00f3 las pericias para establecer la din\u00e1mica del accidente y as\u00ed establecer las responsabilidades en el mortal atropello.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Equipo de emergencias fueron alertados en la ma\u00f1ana de ayer martes de un atropello en las inmediaciones de Vicu\u00f1a Mackenna en Hurtado y Correa, el cual dej\u00f3 como resultado el fallecimiento de un hombre adulto. De acuerdo a los antecedentes preliminares y declaraci\u00f3n del conductor involucrado, la v\u00edctima se encontraba tendida sobre la calzada al<\/p>\n<div class=\"read-more-wrapper\"><a class=\"read-more\" href=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/\" title=\"Leer m\u00e1s\"> <span class=\"button \">Leer m\u00e1s<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":19305,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,3],"tags":[],"class_list":["post-19336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-policial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros - Diario El Labrador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros - Diario El Labrador\" \/>\n<meta property=\"og:description\" content=\"Equipo de emergencias fueron alertados en la ma\u00f1ana de ayer martes de un atropello en las inmediaciones de Vicu\u00f1a Mackenna en Hurtado y Correa, el cual dej\u00f3 como resultado el fallecimiento de un hombre adulto. De acuerdo a los antecedentes preliminares y declaraci\u00f3n del conductor involucrado, la v\u00edctima se encontraba tendida sobre la calzada al Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Labrador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/profile.php?id=61576120840621\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T22:47:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T22:48:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Una-persona-fallecida-deja-atropello-en-Vicuna-Mackenna-sector-Los-Cruceros.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ElLabradorOf\" \/>\n<meta name=\"twitter:site\" content=\"@ElLabradorOf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/\"},\"author\":{\"name\":\"Editor\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/person\\\/bc25ff80b4563f9c7f4bd7855df01685\"},\"headline\":\"Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros\",\"datePublished\":\"2026-05-12T22:47:58+00:00\",\"dateModified\":\"2026-05-12T22:48:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/\"},\"wordCount\":136,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Una-persona-fallecida-deja-atropello-en-Vicuna-Mackenna-sector-Los-Cruceros.jpg\",\"articleSection\":[\"Destacados\",\"Policial\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/\",\"name\":\"Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros - Diario El Labrador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Una-persona-fallecida-deja-atropello-en-Vicuna-Mackenna-sector-Los-Cruceros.jpg\",\"datePublished\":\"2026-05-12T22:47:58+00:00\",\"dateModified\":\"2026-05-12T22:48:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Una-persona-fallecida-deja-atropello-en-Vicuna-Mackenna-sector-Los-Cruceros.jpg\",\"contentUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Una-persona-fallecida-deja-atropello-en-Vicuna-Mackenna-sector-Los-Cruceros.jpg\",\"width\":696,\"height\":367},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diarioellabrador.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#website\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/\",\"name\":\"Diario El Labrador\",\"description\":\"Haciendo noticia desde 1921\",\"publisher\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diarioellabrador.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\",\"name\":\"Diario El Labrador\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-Logo-Icono.png\",\"contentUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-Logo-Icono.png\",\"width\":512,\"height\":512,\"caption\":\"Diario El Labrador\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/profile.php?id=61576120840621\",\"https:\\\/\\\/x.com\\\/ElLabradorOf\",\"https:\\\/\\\/www.instagram.com\\\/diarioellabradoroficial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/person\\\/bc25ff80b4563f9c7f4bd7855df01685\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros - Diario El Labrador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/","og_locale":"es_ES","og_type":"article","og_title":"Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros - Diario El Labrador","og_description":"Equipo de emergencias fueron alertados en la ma\u00f1ana de ayer martes de un atropello en las inmediaciones de Vicu\u00f1a Mackenna en Hurtado y Correa, el cual dej\u00f3 como resultado el fallecimiento de un hombre adulto. De acuerdo a los antecedentes preliminares y declaraci\u00f3n del conductor involucrado, la v\u00edctima se encontraba tendida sobre la calzada al Leer m\u00e1s","og_url":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/","og_site_name":"Diario El Labrador","article_publisher":"https:\/\/web.facebook.com\/profile.php?id=61576120840621","article_published_time":"2026-05-12T22:47:58+00:00","article_modified_time":"2026-05-12T22:48:01+00:00","og_image":[{"width":696,"height":367,"url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Una-persona-fallecida-deja-atropello-en-Vicuna-Mackenna-sector-Los-Cruceros.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_creator":"@ElLabradorOf","twitter_site":"@ElLabradorOf","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/#article","isPartOf":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/"},"author":{"name":"Editor","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/person\/bc25ff80b4563f9c7f4bd7855df01685"},"headline":"Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros","datePublished":"2026-05-12T22:47:58+00:00","dateModified":"2026-05-12T22:48:01+00:00","mainEntityOfPage":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/"},"wordCount":136,"commentCount":0,"publisher":{"@id":"https:\/\/diarioellabrador.cl\/#organization"},"image":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Una-persona-fallecida-deja-atropello-en-Vicuna-Mackenna-sector-Los-Cruceros.jpg","articleSection":["Destacados","Policial"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/","url":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/","name":"Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros - Diario El Labrador","isPartOf":{"@id":"https:\/\/diarioellabrador.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/#primaryimage"},"image":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Una-persona-fallecida-deja-atropello-en-Vicuna-Mackenna-sector-Los-Cruceros.jpg","datePublished":"2026-05-12T22:47:58+00:00","dateModified":"2026-05-12T22:48:01+00:00","breadcrumb":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/#primaryimage","url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Una-persona-fallecida-deja-atropello-en-Vicuna-Mackenna-sector-Los-Cruceros.jpg","contentUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Una-persona-fallecida-deja-atropello-en-Vicuna-Mackenna-sector-Los-Cruceros.jpg","width":696,"height":367},{"@type":"BreadcrumbList","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/una-persona-fallecida-deja-atropello-en-vicuna-mackenna-sector-los-cruceros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioellabrador.cl\/"},{"@type":"ListItem","position":2,"name":"Una persona fallecida deja atropello en Vicu\u00f1a Mackenna sector Los Cruceros"}]},{"@type":"WebSite","@id":"https:\/\/diarioellabrador.cl\/#website","url":"https:\/\/diarioellabrador.cl\/","name":"Diario El Labrador","description":"Haciendo noticia desde 1921","publisher":{"@id":"https:\/\/diarioellabrador.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioellabrador.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diarioellabrador.cl\/#organization","name":"Diario El Labrador","url":"https:\/\/diarioellabrador.cl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/logo\/image\/","url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2025\/02\/cropped-Logo-Icono.png","contentUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2025\/02\/cropped-Logo-Icono.png","width":512,"height":512,"caption":"Diario El Labrador"},"image":{"@id":"https:\/\/diarioellabrador.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/profile.php?id=61576120840621","https:\/\/x.com\/ElLabradorOf","https:\/\/www.instagram.com\/diarioellabradoroficial\/"]},{"@type":"Person","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/person\/bc25ff80b4563f9c7f4bd7855df01685","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/diarioellabrador.cl\/index.php\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/comments?post=19336"}],"version-history":[{"count":1,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19336\/revisions"}],"predecessor-version":[{"id":19337,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19336\/revisions\/19337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/media\/19305"}],"wp:attachment":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/media?parent=19336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/categories?post=19336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/tags?post=19336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}