{"id":19334,"date":"2026-05-12T18:47:04","date_gmt":"2026-05-12T22:47:04","guid":{"rendered":"https:\/\/diarioellabrador.cl\/?p=19334"},"modified":"2026-05-12T18:47:08","modified_gmt":"2026-05-12T22:47:08","slug":"tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores","status":"publish","type":"post","link":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/","title":{"rendered":"Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores"},"content":{"rendered":"\n<p><strong>Autor: <\/strong><a href=\"https:\/\/www.caballoyrodeo.cl\/portal_rodeo\/site\/artic\/20240205\/pags\/20240205103254.html\">H\u00e9ctor Parraguirre Jara<\/a><\/p>\n\n\n\n<p>El <strong>Consejo T\u00e9cnico<\/strong> ser\u00e1 la primera actividad que la <strong>Federaci\u00f3n Criadores de Caballos Raza Chilena<\/strong> tendr\u00e1 en <a href=\"https:\/\/www.caballoyrodeo.cl\/portal_rodeo\/site\/artic\/20260512\/pags\/20260512130024.html\"><strong>un intenso programa<\/strong><\/a>a desarrollarse en el <strong>Hotel Sheraton de Santiago<\/strong>, y que en esta versi\u00f3n 2026 tratar\u00e1 importantes temas de bienestar animal y de mucha actualidad.<\/p>\n\n\n\n<p>Las charlas que se dictar\u00e1n a partir de las 09:00 horas ser\u00e1n:<\/p>\n\n\n\n<p><strong>&#8211; \u00abTrazabilidad equina y su puesta en marcha en el marco de la Resoluci\u00f3n SAG N\u00b01221\/2026\u00bb, <\/strong>a cargo de<strong> Javiera Ruiz de Gamboa Villagr\u00e1n, <\/strong>profesional de Servicio Agr\u00edcola y Ganadero (SAG);<\/p>\n\n\n\n<p><strong>&#8211; \u00abCuidado de aplomos en potrillos desde el nacimiento hasta el primer a\u00f1o de vida\u00bb, <\/strong>por el <strong>Dr. Sergio Beltr\u00e1n S\u00e1nchez;<\/strong> y<\/p>\n\n\n\n<p><strong>&#8211; \u00abBienestar animal en la crianza del Caballo de Raza Chilena: manejo de la yegua desde la cruza hasta el primer a\u00f1o de vida de la cr\u00eda\u00bb, <\/strong>que expondr\u00e1 la <strong>Dra. Mar\u00eda Elina Tejeda, <\/strong>m\u00e9dico veterinaria.<\/p>\n\n\n\n<p>Para profundizar en esta tabla de temas, trabajada en conjunto por la <strong>Comisi\u00f3n T\u00e9cnica<\/strong>, que presidente el director de la Federaci\u00f3n <strong>Rodrigo Mu\u00f1oz<\/strong>, y el Departamento T\u00e9cnico de la instituci\u00f3n, se refiri\u00f3 el gerente t\u00e9cnico y de desarrollo deportivo, <strong>Gabriel Varela<\/strong>.<\/p>\n\n\n\n<p>\u00abHemos vuelto un poquito a la esencia de los Consejos T\u00e9cnicos con temas que podamos llevar a las bases. La idea es volver un poco al origen del Consejo T\u00e9cnico, dando una pincelada de ciertos temas que debiesen llevar los presidentes a sus bases. Y esto es netamente en base a la retroalimentaci\u00f3n que hemos tenido de distintos criadores, en las diferentes visitas que hemos hecho, y de ah\u00ed vienen dos temas bien t\u00e9cnicos y uno de contingencia\u00bb, explic\u00f3 Varela.<\/p>\n\n\n\n<p>\u00abEn los temas t\u00e9cnicos, tenemos el del cuidado de los aplomos en los potrillos. Hemos conversado en reiteradas ocasiones sobre la importancia que tiene cuidar los aplomos desde el d\u00eda del nacimiento, porque ah\u00ed t\u00fa te juegas todo el futuro de tu ejemplar. Entonces, conversamos con un profesional de primera l\u00ednea como Sergio Beltr\u00e1n, quien accedi\u00f3 a acompa\u00f1arnos y poder abordar este tema con respecto al cuidado que hay que tener en los cascos del potrillo, ya que desde esta base vamos a proyectar nuestro futuro caballo para las distintas competencias ecuestres en las cuales se puede desenvolver el caballo chileno\u00bb, continu\u00f3.<\/p>\n\n\n\n<p>\u00abEl otro tema t\u00e9cnico lo va a tratar la doctora Mar\u00eda Elina Tejeda, que es una profesional del rubro de bienestar. Ella tiene varios diplomados de bienestar animal y vamos a conversar del bienestar de la madre, el bienestar de la yegua y su cr\u00eda desde el momento de la cruza hasta el primer a\u00f1o de vida., todo lo que debi\u00e9semos cuidar, c\u00f3mo velar porque este potrillo y esta madre est\u00e9n dentro de la normativa de bienestar; de los espacios, la nutrici\u00f3n, todo lo que involucra el cuidado de la madre y su cr\u00eda\u00bb, complet\u00f3 Varela.<\/p>\n\n\n\n<p>En cuanto al tema que va a abrir el Consejo T\u00e9cnico 2026, Gabriel Varela apunt\u00f3 que \u00ablo va a dictar Javiera Ruiz de Gamboa, una funcionaria del Servicio Agr\u00edcola y Ganadero con quien hemos estado trabajando muy fuerte en el \u00faltimo tiempo. Es el tema de la trazabilidad equina, una normativa vigente que ya est\u00e1 ejecut\u00e1ndose, en una especie de marcha blanca, pero existe un poco de desconocimiento de parte de los distintos criadores de caballos y eso tambi\u00e9n lo hemos recogido en base a las consultas que nos han llegado, tanto a nuestras redes como llamadas directas de criadores, de presidentes de asociaciones, para poder informar un poco m\u00e1s de qu\u00e9 implica esta trazabilidad\u00bb.<\/p>\n\n\n\n<p>\u00abSi bien no es un tema nuevo para nosotros como criadores de caballos de raza chilena, ya que todos nuestros caballos tienen un microchip incorporado para un sistema de identificaci\u00f3n, hay cierta normativa que vamos a tener que acostumbrarnos a ejercer para el movimiento de los animales. Y todo esto nace de la necesidad de tener una trazabilidad, como bien se\u00f1ala su nombre, para saber qu\u00e9 movimientos tenemos. Esta trazabilidad va a poder se\u00f1alar a trav\u00e9s de un sistema, ingresando un n\u00famero de chip, qu\u00e9 movimientos tuvo el caballo\u00bb, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>\u00abEsto nace por la<strong> Anemia Infecciosa Equina<\/strong> que ha crecido. Con esto vamos a tener una trazabilidad en nuestros caballos y tambi\u00e9n en todos los ejemplares a nivel pa\u00eds, porque el proyecto se\u00f1ala que todos los \u00e9quidos, no solamente los caballos, sino tambi\u00e9n asnos y mulares, debiesen tambi\u00e9n tener a futuro un sistema de identificaci\u00f3n\u00bb, complement\u00f3.<\/p>\n\n\n\n<p>Sobre ese \u00faltimo punto, Varela dijo que\u00bb ah\u00ed hay algo importante, porque muchas personas piensan que este chip que va a incorporar el Servicio Agr\u00edcola y Ganadero, les va a servir como GPS. Eso no es as\u00ed. El sistema de chip es netamente identificatorio, no le va a permitir rastrear un animal\u00bb.<\/p>\n\n\n\n<p>El gerente t\u00e9cnico de la Federaci\u00f3n se\u00f1al\u00f3 finalmente que \u00abvamos a tener una ma\u00f1ana bien intensa. Van a ser charlas de 30 minutos y luego 15 minutos de interacci\u00f3n, para poder conversar sobre estos temas, quiz\u00e1s no en la profundidad que quisi\u00e9ramos darle, en honor al tiempo, pero posiblemente el d\u00eda de ma\u00f1ana podemos contar con estos profesionales para poder dictar una charla a nivel regional o c\u00f3mo nos vayamos organizando con nuestras bases, para llevar esta informaci\u00f3n a todos los criadores del pa\u00eds\u00bb.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autor: H\u00e9ctor Parraguirre Jara El Consejo T\u00e9cnico ser\u00e1 la primera actividad que la Federaci\u00f3n Criadores de Caballos Raza Chilena tendr\u00e1 en un intenso programaa desarrollarse en el Hotel Sheraton de Santiago, y que en esta versi\u00f3n 2026 tratar\u00e1 importantes temas de bienestar animal y de mucha actualidad. Las charlas que se dictar\u00e1n a partir de<\/p>\n<div class=\"read-more-wrapper\"><a class=\"read-more\" href=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/\" title=\"Leer m\u00e1s\"> <span class=\"button \">Leer m\u00e1s<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":19320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-19334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rodeo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores - Diario El Labrador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores - Diario El Labrador\" \/>\n<meta property=\"og:description\" content=\"Autor: H\u00e9ctor Parraguirre Jara El Consejo T\u00e9cnico ser\u00e1 la primera actividad que la Federaci\u00f3n Criadores de Caballos Raza Chilena tendr\u00e1 en un intenso programaa desarrollarse en el Hotel Sheraton de Santiago, y que en esta versi\u00f3n 2026 tratar\u00e1 importantes temas de bienestar animal y de mucha actualidad. Las charlas que se dictar\u00e1n a partir de Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Labrador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/profile.php?id=61576120840621\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T22:47:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T22:47:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Tres-charlas-tecnicas-incluira-el-Consejo-Tecnico-de-la-Federacion-de-Criadores.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"389\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ElLabradorOf\" \/>\n<meta name=\"twitter:site\" content=\"@ElLabradorOf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/\"},\"author\":{\"name\":\"Editor\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/person\\\/bc25ff80b4563f9c7f4bd7855df01685\"},\"headline\":\"Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores\",\"datePublished\":\"2026-05-12T22:47:04+00:00\",\"dateModified\":\"2026-05-12T22:47:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/\"},\"wordCount\":946,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Tres-charlas-tecnicas-incluira-el-Consejo-Tecnico-de-la-Federacion-de-Criadores.jpg\",\"articleSection\":[\"Rodeo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/\",\"name\":\"Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores - Diario El Labrador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Tres-charlas-tecnicas-incluira-el-Consejo-Tecnico-de-la-Federacion-de-Criadores.jpg\",\"datePublished\":\"2026-05-12T22:47:04+00:00\",\"dateModified\":\"2026-05-12T22:47:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Tres-charlas-tecnicas-incluira-el-Consejo-Tecnico-de-la-Federacion-de-Criadores.jpg\",\"contentUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Tres-charlas-tecnicas-incluira-el-Consejo-Tecnico-de-la-Federacion-de-Criadores.jpg\",\"width\":750,\"height\":389},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/2026\\\/05\\\/12\\\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diarioellabrador.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#website\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/\",\"name\":\"Diario El Labrador\",\"description\":\"Haciendo noticia desde 1921\",\"publisher\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diarioellabrador.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#organization\",\"name\":\"Diario El Labrador\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-Logo-Icono.png\",\"contentUrl\":\"https:\\\/\\\/diarioellabrador.cl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-Logo-Icono.png\",\"width\":512,\"height\":512,\"caption\":\"Diario El Labrador\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/profile.php?id=61576120840621\",\"https:\\\/\\\/x.com\\\/ElLabradorOf\",\"https:\\\/\\\/www.instagram.com\\\/diarioellabradoroficial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diarioellabrador.cl\\\/#\\\/schema\\\/person\\\/bc25ff80b4563f9c7f4bd7855df01685\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\\\/\\\/diarioellabrador.cl\\\/index.php\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores - Diario El Labrador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/","og_locale":"es_ES","og_type":"article","og_title":"Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores - Diario El Labrador","og_description":"Autor: H\u00e9ctor Parraguirre Jara El Consejo T\u00e9cnico ser\u00e1 la primera actividad que la Federaci\u00f3n Criadores de Caballos Raza Chilena tendr\u00e1 en un intenso programaa desarrollarse en el Hotel Sheraton de Santiago, y que en esta versi\u00f3n 2026 tratar\u00e1 importantes temas de bienestar animal y de mucha actualidad. Las charlas que se dictar\u00e1n a partir de Leer m\u00e1s","og_url":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/","og_site_name":"Diario El Labrador","article_publisher":"https:\/\/web.facebook.com\/profile.php?id=61576120840621","article_published_time":"2026-05-12T22:47:04+00:00","article_modified_time":"2026-05-12T22:47:08+00:00","og_image":[{"width":750,"height":389,"url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Tres-charlas-tecnicas-incluira-el-Consejo-Tecnico-de-la-Federacion-de-Criadores.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_creator":"@ElLabradorOf","twitter_site":"@ElLabradorOf","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/#article","isPartOf":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/"},"author":{"name":"Editor","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/person\/bc25ff80b4563f9c7f4bd7855df01685"},"headline":"Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores","datePublished":"2026-05-12T22:47:04+00:00","dateModified":"2026-05-12T22:47:08+00:00","mainEntityOfPage":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/"},"wordCount":946,"commentCount":0,"publisher":{"@id":"https:\/\/diarioellabrador.cl\/#organization"},"image":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Tres-charlas-tecnicas-incluira-el-Consejo-Tecnico-de-la-Federacion-de-Criadores.jpg","articleSection":["Rodeo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/","url":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/","name":"Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores - Diario El Labrador","isPartOf":{"@id":"https:\/\/diarioellabrador.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/#primaryimage"},"image":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Tres-charlas-tecnicas-incluira-el-Consejo-Tecnico-de-la-Federacion-de-Criadores.jpg","datePublished":"2026-05-12T22:47:04+00:00","dateModified":"2026-05-12T22:47:08+00:00","breadcrumb":{"@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/#primaryimage","url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Tres-charlas-tecnicas-incluira-el-Consejo-Tecnico-de-la-Federacion-de-Criadores.jpg","contentUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2026\/05\/Tres-charlas-tecnicas-incluira-el-Consejo-Tecnico-de-la-Federacion-de-Criadores.jpg","width":750,"height":389},{"@type":"BreadcrumbList","@id":"https:\/\/diarioellabrador.cl\/index.php\/2026\/05\/12\/tres-charlas-tecnicas-incluira-el-consejo-tecnico-de-la-federacion-de-criadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioellabrador.cl\/"},{"@type":"ListItem","position":2,"name":"Tres charlas t\u00e9cnicas incluir\u00e1 el Consejo T\u00e9cnico de la Federaci\u00f3n de Criadores"}]},{"@type":"WebSite","@id":"https:\/\/diarioellabrador.cl\/#website","url":"https:\/\/diarioellabrador.cl\/","name":"Diario El Labrador","description":"Haciendo noticia desde 1921","publisher":{"@id":"https:\/\/diarioellabrador.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioellabrador.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diarioellabrador.cl\/#organization","name":"Diario El Labrador","url":"https:\/\/diarioellabrador.cl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/logo\/image\/","url":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2025\/02\/cropped-Logo-Icono.png","contentUrl":"https:\/\/diarioellabrador.cl\/wp-content\/uploads\/2025\/02\/cropped-Logo-Icono.png","width":512,"height":512,"caption":"Diario El Labrador"},"image":{"@id":"https:\/\/diarioellabrador.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/profile.php?id=61576120840621","https:\/\/x.com\/ElLabradorOf","https:\/\/www.instagram.com\/diarioellabradoroficial\/"]},{"@type":"Person","@id":"https:\/\/diarioellabrador.cl\/#\/schema\/person\/bc25ff80b4563f9c7f4bd7855df01685","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/109c326cf2be5c04f048c2c2a2b8b6ef44bf3d8d1d3d4c55d0ac40c4bc994684?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/diarioellabrador.cl\/index.php\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/comments?post=19334"}],"version-history":[{"count":1,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19334\/revisions"}],"predecessor-version":[{"id":19335,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/posts\/19334\/revisions\/19335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/media\/19320"}],"wp:attachment":[{"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/media?parent=19334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/categories?post=19334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioellabrador.cl\/index.php\/wp-json\/wp\/v2\/tags?post=19334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}